{"id":3363,"count":1,"description":"","link":"https:\/\/mascherpa.it\/en\/argomenti\/mechanical-components\/shock-absorbers-and-dampers\/","name":"Shock Absorbers and Dampers","slug":"shock-absorbers-and-dampers","taxonomy":"category","parent":3361,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Articoli su Shock Absorbers and Dampers | Mascherpa s.p.a<\/title>\n<meta name=\"description\" content=\"Scopri tutti gli articoli su Shock Absorbers and Dampers di Mascherpa s.p.a. Contattaci per maggiori info.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mascherpa.it\/en\/argomenti\/mechanical-components\/shock-absorbers-and-dampers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Articoli su Shock Absorbers and Dampers | Mascherpa s.p.a\" \/>\n<meta property=\"og:description\" content=\"Scopri tutti gli articoli su Shock Absorbers and Dampers di Mascherpa s.p.a. Contattaci per maggiori info.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mascherpa.it\/en\/argomenti\/mechanical-components\/shock-absorbers-and-dampers\/\" \/>\n<meta property=\"og:site_name\" content=\"Mascherpa s.p.a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/argomenti\\\/mechanical-components\\\/shock-absorbers-and-dampers\\\/\",\"url\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/argomenti\\\/mechanical-components\\\/shock-absorbers-and-dampers\\\/\",\"name\":\"Articoli su Shock Absorbers and Dampers | Mascherpa s.p.a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#website\"},\"description\":\"Scopri tutti gli articoli su Shock Absorbers and Dampers di Mascherpa s.p.a. Contattaci per maggiori info.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/argomenti\\\/mechanical-components\\\/shock-absorbers-and-dampers\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/argomenti\\\/mechanical-components\\\/shock-absorbers-and-dampers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"mascherpa.it\",\"item\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/mascherpa.it\\\/argomenti\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Industrial Lubricants\",\"item\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/argomenti\\\/industrial-lubricants\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Meccanica\",\"item\":\"https:\\\/\\\/mascherpa.it\\\/argomenti\\\/prodotti\\\/lubrificanti-industriali\\\/meccanica-superfici\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Mechanical components\",\"item\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/argomenti\\\/mechanical-components\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Shock Absorbers and Dampers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/\",\"name\":\"Mascherpa s.p.a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Articoli su Shock Absorbers and Dampers | Mascherpa s.p.a","description":"Scopri tutti gli articoli su Shock Absorbers and Dampers di Mascherpa s.p.a. Contattaci per maggiori info.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mascherpa.it\/en\/argomenti\/mechanical-components\/shock-absorbers-and-dampers\/","og_locale":"en_US","og_type":"article","og_title":"Articoli su Shock Absorbers and Dampers | Mascherpa s.p.a","og_description":"Scopri tutti gli articoli su Shock Absorbers and Dampers di Mascherpa s.p.a. Contattaci per maggiori info.","og_url":"https:\/\/mascherpa.it\/en\/argomenti\/mechanical-components\/shock-absorbers-and-dampers\/","og_site_name":"Mascherpa s.p.a","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mascherpa.it\/en\/argomenti\/mechanical-components\/shock-absorbers-and-dampers\/","url":"https:\/\/mascherpa.it\/en\/argomenti\/mechanical-components\/shock-absorbers-and-dampers\/","name":"Articoli su Shock Absorbers and Dampers | Mascherpa s.p.a","isPartOf":{"@id":"https:\/\/mascherpa.it\/en\/#website"},"description":"Scopri tutti gli articoli su Shock Absorbers and Dampers di Mascherpa s.p.a. Contattaci per maggiori info.","breadcrumb":{"@id":"https:\/\/mascherpa.it\/en\/argomenti\/mechanical-components\/shock-absorbers-and-dampers\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/mascherpa.it\/en\/argomenti\/mechanical-components\/shock-absorbers-and-dampers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"mascherpa.it","item":"https:\/\/mascherpa.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/mascherpa.it\/argomenti\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Industrial Lubricants","item":"https:\/\/mascherpa.it\/en\/argomenti\/industrial-lubricants\/"},{"@type":"ListItem","position":4,"name":"Meccanica","item":"https:\/\/mascherpa.it\/argomenti\/prodotti\/lubrificanti-industriali\/meccanica-superfici\/"},{"@type":"ListItem","position":5,"name":"Mechanical components","item":"https:\/\/mascherpa.it\/en\/argomenti\/mechanical-components\/"},{"@type":"ListItem","position":6,"name":"Shock Absorbers and Dampers"}]},{"@type":"WebSite","@id":"https:\/\/mascherpa.it\/en\/#website","url":"https:\/\/mascherpa.it\/en\/","name":"Mascherpa s.p.a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mascherpa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/categories\/3363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/categories\/3361"}],"wp:post_type":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/posts?categories=3363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}