{"id":21759,"date":"2017-09-23T17:04:34","date_gmt":"2017-09-23T17:04:34","guid":{"rendered":"https:\/\/mascherpa.it\/non-categorizzato\/"},"modified":"2023-12-21T11:07:27","modified_gmt":"2023-12-21T11:07:27","slug":"merger-between-dow-and-dupont","status":"publish","type":"post","link":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/","title":{"rendered":"MERGER BETWEEN DOW AND DUPONT"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;17003&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<div>The merger between Dow Chemical and Dupont de Nemours was completed on August 31.<\/div>\n<div>DowDupont, ranked among the world&#8217;s top chemical giants,incorporates the synergistic portfolios of Dow and DuPont, and is composed of three independent divisions-Agriculture, Material Sciences, and Specialty Products-leading in their respective fields.<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/\" class=\"excerpt\">[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;17003&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221;&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":21213,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wpb_vc_js_status":"","_wpb_shortcodes_custom_css":""},"categories":[3189],"tags":[3223,3252],"class_list":["post-21759","post","type-post","status-publish","format-standard","has-post-thumbnail","category-conttto","tag-dow-en","tag-dupont-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MERGER BETWEEN DOW AND DUPONT | Mascherpa s.p.a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MERGER BETWEEN DOW AND DUPONT | Mascherpa s.p.a\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;17003&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/\" \/>\n<meta property=\"og:site_name\" content=\"Mascherpa s.p.a\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-23T17:04:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-21T11:07:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mascherpa.it\/wp-content\/uploads\/2017\/09\/image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"316\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mascherpa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mascherpa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/\"},\"author\":{\"name\":\"Mascherpa\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#\\\/schema\\\/person\\\/4eb665b7a59162f0f3162863f6eeac76\"},\"headline\":\"MERGER BETWEEN DOW AND DUPONT\",\"datePublished\":\"2017-09-23T17:04:34+00:00\",\"dateModified\":\"2023-12-21T11:07:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/\"},\"wordCount\":349,\"image\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mascherpa.it\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/image.png\",\"keywords\":[\"Dow\",\"Dupont\"],\"articleSection\":[\"CONT@TTO\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/\",\"url\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/\",\"name\":\"MERGER BETWEEN DOW AND DUPONT | Mascherpa s.p.a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mascherpa.it\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/image.png\",\"datePublished\":\"2017-09-23T17:04:34+00:00\",\"dateModified\":\"2023-12-21T11:07:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#\\\/schema\\\/person\\\/4eb665b7a59162f0f3162863f6eeac76\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mascherpa.it\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/image.png\",\"contentUrl\":\"https:\\\/\\\/mascherpa.it\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/image.png\",\"width\":600,\"height\":316},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/merger-between-dow-and-dupont\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"mascherpa.it\",\"item\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MERGER BETWEEN DOW AND DUPONT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/\",\"name\":\"Mascherpa s.p.a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#\\\/schema\\\/person\\\/4eb665b7a59162f0f3162863f6eeac76\",\"name\":\"Mascherpa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g\",\"caption\":\"Mascherpa\"},\"url\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/author\\\/mascherpa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MERGER BETWEEN DOW AND DUPONT | Mascherpa s.p.a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/","og_locale":"en_US","og_type":"article","og_title":"MERGER BETWEEN DOW AND DUPONT | Mascherpa s.p.a","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;17003&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221;...","og_url":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/","og_site_name":"Mascherpa s.p.a","article_published_time":"2017-09-23T17:04:34+00:00","article_modified_time":"2023-12-21T11:07:27+00:00","og_image":[{"width":600,"height":316,"url":"https:\/\/mascherpa.it\/wp-content\/uploads\/2017\/09\/image.png","type":"image\/png"}],"author":"Mascherpa","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Mascherpa","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/#article","isPartOf":{"@id":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/"},"author":{"name":"Mascherpa","@id":"https:\/\/mascherpa.it\/en\/#\/schema\/person\/4eb665b7a59162f0f3162863f6eeac76"},"headline":"MERGER BETWEEN DOW AND DUPONT","datePublished":"2017-09-23T17:04:34+00:00","dateModified":"2023-12-21T11:07:27+00:00","mainEntityOfPage":{"@id":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/"},"wordCount":349,"image":{"@id":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/#primaryimage"},"thumbnailUrl":"https:\/\/mascherpa.it\/wp-content\/uploads\/2017\/09\/image.png","keywords":["Dow","Dupont"],"articleSection":["CONT@TTO"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/","url":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/","name":"MERGER BETWEEN DOW AND DUPONT | Mascherpa s.p.a","isPartOf":{"@id":"https:\/\/mascherpa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/#primaryimage"},"image":{"@id":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/#primaryimage"},"thumbnailUrl":"https:\/\/mascherpa.it\/wp-content\/uploads\/2017\/09\/image.png","datePublished":"2017-09-23T17:04:34+00:00","dateModified":"2023-12-21T11:07:27+00:00","author":{"@id":"https:\/\/mascherpa.it\/en\/#\/schema\/person\/4eb665b7a59162f0f3162863f6eeac76"},"breadcrumb":{"@id":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/#primaryimage","url":"https:\/\/mascherpa.it\/wp-content\/uploads\/2017\/09\/image.png","contentUrl":"https:\/\/mascherpa.it\/wp-content\/uploads\/2017\/09\/image.png","width":600,"height":316},{"@type":"BreadcrumbList","@id":"https:\/\/mascherpa.it\/en\/blog\/merger-between-dow-and-dupont\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"mascherpa.it","item":"https:\/\/mascherpa.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/mascherpa.it\/en\/blog\/"},{"@type":"ListItem","position":3,"name":"MERGER BETWEEN DOW AND DUPONT"}]},{"@type":"WebSite","@id":"https:\/\/mascherpa.it\/en\/#website","url":"https:\/\/mascherpa.it\/en\/","name":"Mascherpa s.p.a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mascherpa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/mascherpa.it\/en\/#\/schema\/person\/4eb665b7a59162f0f3162863f6eeac76","name":"Mascherpa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g","caption":"Mascherpa"},"url":"https:\/\/mascherpa.it\/en\/author\/mascherpa\/"}]}},"_links":{"self":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/posts\/21759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/comments?post=21759"}],"version-history":[{"count":11,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/posts\/21759\/revisions"}],"predecessor-version":[{"id":21842,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/posts\/21759\/revisions\/21842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/media\/21213"}],"wp:attachment":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/media?parent=21759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/categories?post=21759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/tags?post=21759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}