{"id":36871,"date":"2026-04-02T09:00:29","date_gmt":"2026-04-02T09:00:29","guid":{"rendered":"https:\/\/mascherpa.it\/?p=36871"},"modified":"2026-04-02T14:01:49","modified_gmt":"2026-04-02T14:01:49","slug":"36871","status":"publish","type":"post","link":"https:\/\/mascherpa.it\/en\/blog\/36871\/","title":{"rendered":"ARALDITE\u00ae 2051 A\/B approved ECS 7409 Airbus Helicopters"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#F7F7F7&#8243; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;15px&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;clip-path&#8221; clip_path_animation_type=&#8221;default&#8221; clip_path_animation_applies=&#8221;default&#8221; clip_path_animation_addon=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>Key Points<\/h2>\n[\/vc_column_text]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-check\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> \n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>ARALDITE\u00ae 2051 A\/B has been approved ECS 7409 Airbus Helicopters<\/b><span style=\"font-weight: 400;\"> for <\/span><b>structural bonding<\/b><span style=\"font-weight: 400;\"> in aerospace applications.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Methacrylic adhesive<\/b><span style=\"font-weight: 400;\"> with <\/span><b>ultra-fast curing<\/b><span style=\"font-weight: 400;\"> designed for extreme operating conditions.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Reliable performance between <\/span><b>-55\u00b0C and +90\u00b0C<\/b><span style=\"font-weight: 400;\"> even in <\/span><b>humid environments<\/b><span style=\"font-weight: 400;\"> or at <\/span><b>low temperatures<\/b><span style=\"font-weight: 400;\">.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ideal for <\/span><b>maintenance, repair, and production<\/b><span style=\"font-weight: 400;\"> with direct field application.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>High mechanical performance<\/b> and simplified application on metals, composites, and thermoplastics.<\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_1=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<a href=\"https:\/\/mascherpa.it\/en\/products\/araldite-2051\/\"><b>ARALDITE\u00ae 2051<\/b><\/a><b> A\/B <\/b><span style=\"font-weight: 400;\">has been approved in accordance with <\/span><b>ECS 7409 Edition A<\/b><span style=\"font-weight: 400;\"> specification from <\/span><b>Airbus Helicopters<\/b><span style=\"font-weight: 400;\"> for <\/span><b>very <\/b><span style=\"font-weight: 400;\">fast-curing<\/span><b> adhesives<\/b><span style=\"font-weight: 400;\">.<\/span>[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f7f7f7&#8243; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;15px&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;clip-path&#8221; clip_path_animation_type=&#8221;default&#8221; clip_path_animation_applies=&#8221;default&#8221; clip_path_animation_addon=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2 class=\"p3\">Index<\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#1\"><span style=\"font-weight: 400;\">Aerospace qualification for critical structural bonding<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#2\"><span style=\"font-weight: 400;\">Rapid structural repair for challenging environments<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#3\"><span style=\"font-weight: 400;\">ARALDITE\u00ae 2051 A\/B features<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"#4\"><span style=\"font-weight: 400;\">Discover all solutions in the ARALDITE\u00ae range<\/span><\/a><\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;1&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2><strong>Aerospace qualification for critical structural bonding<\/strong><\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"font-weight: 400;\">The product  <\/span><b>ARALDITE\u00ae 2051 A\/B<\/b><span style=\"font-weight: 400;\">, developed by  <\/span><a href=\"https:\/\/mascherpa.it\/guida-prodotto\/marchi\/huntsman\/\"><b>Huntsman<\/b><\/a><span style=\"font-weight: 400;\">, has been approved in accordance with the stringent  <\/span><b>aerospace specification ECS 7409<\/b> <b>Edition A<\/b><span style=\"font-weight: 400;\">  for  <\/span><a href=\"https:\/\/mascherpa.it\/guida-prodotto\/adesivi-industriali\/adesivi-metacrilici\/\"><b>methacrylic adhesives <\/b><\/a><span style=\"font-weight: 400;\">in  <\/span><b>paste<\/b><span style=\"font-weight: 400;\">  extreme conditions <\/span><b>ultra-fast curing<\/b><span style=\"font-weight: 400;\">.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">This <\/span><b>certification<\/b><span style=\"font-weight: 400;\"> is valid for use in applications requiring reliable <\/span><b>structural support<\/b><span style=\"font-weight: 400;\"> in <\/span><b>extreme conditions<\/b><span style=\"font-weight: 400;\">, with an <\/span><b>operating temperature<\/b><span style=\"font-weight: 400;\"> range between <\/span><b>-55\u00b0C<\/b><span style=\"font-weight: 400;\"> and <\/span><b>+90\u00b0C<\/b><span style=\"font-weight: 400;\">.<\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][image_with_animation image_url=&#8221;36880&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;20px&#8221; box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;2&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;1&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2><strong>Rapid structural repair for challenging environments<\/strong><\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"font-weight: 400;\">Thanks to its  <\/span><b>accelerated curing<\/b><span style=\"font-weight: 400;\">  capability and its  <\/span><b>performance in humid environments<\/b><span style=\"font-weight: 400;\">  or at  <\/span><b>low temperatures<\/b><span style=\"font-weight: 400;\">,  <\/span><b>ARALDITE\u00ae 2051 A\/B<\/b><span style=\"font-weight: 400;\">  is ideal for  <\/span><b>maintenance<\/b><span style=\"font-weight: 400;\">,  <\/span><b>repair<\/b><span style=\"font-weight: 400;\">  e  <\/span><b>production<\/b><span style=\"font-weight: 400;\">  operations in the <\/span><a href=\"https:\/\/mascherpa.it\/guida-prodotto\/industrie\/aerospaziale-e-difesa\/\"><b>aerospace industry<\/b><\/a><span style=\"font-weight: 400;\">.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Its availability in <\/span><b>cartridges<\/b><span style=\"font-weight: 400;\"> of <\/span><b>50 ml<\/b><span style=\"font-weight: 400;\"> and <\/span><b>380 ml<\/b><span style=\"font-weight: 400;\"> (ref. 4408308 &#8211; pack of <\/span><b>6 x 6 x 50<\/b><span style=\"font-weight: 400;\"> ml) facilitates direct field or on-site application.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">This  <\/span><b>methacrylic adhesive<\/b><span style=\"font-weight: 400;\">  has established itself as a highly reliable  <\/span><b>technical solution<\/b><span style=\"font-weight: 400;\">  for  <\/span><b>structural bonding<\/b><span style=\"font-weight: 400;\">  on materials such as  <\/span><a href=\"https:\/\/mascherpa.it\/guida-prodotto\/adesivi-industriali\/superfici\/metalli\/\"><b>metals<\/b><\/a><span style=\"font-weight: 400;\">,  <\/span><a href=\"https:\/\/mascherpa.it\/guida-prodotto\/adesivi-industriali\/superfici\/adesivi-per-compositi\/\"><b>composites<\/b><\/a><span style=\"font-weight: 400;\"> or <\/span><b>thermoplastics<\/b><span style=\"font-weight: 400;\">, even in  <\/span><b>adverse conditions<\/b><span style=\"font-weight: 400;\">.<\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;3&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;1&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2><strong>ARALDITE\u00ae 2051 A\/B features<\/strong><\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b>ARALDITE\u00ae 2051 A\/B<\/b><span style=\"font-weight: 400;\"> is a <\/span><b>two-component methacrylic structural adhesive<\/b><span style=\"font-weight: 400;\"> with <\/span><b>fast polymerization<\/b><span style=\"font-weight: 400;\">, designed to operate between <\/span><b>0\u00b0C and 40\u00b0C<\/b><span style=\"font-weight: 400;\"> with working times under <\/span><b>10 minutes<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">This <\/span><a href=\"https:\/\/mascherpa.it\/guida-prodotto\/adesivi-industriali\/adesivi-strutturali\/\"><b>structural adhesive<\/b><\/a><span style=\"font-weight: 400;\"> ensures <\/span><b>high mechanical performance<\/b><span style=\"font-weight: 400;\">, with <\/span><b>tensile strength<\/b><span style=\"font-weight: 400;\"> up to <\/span><b>40 MPa<\/b><span style=\"font-weight: 400;\"> and excellent <\/span><b>shear resistance<\/b><span style=\"font-weight: 400;\">, maintaining <\/span><b>stability<\/b><span style=\"font-weight: 400;\"> even in aggressive environmental conditions.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">The <\/span><b>non-sag formulation<\/b><span style=\"font-weight: 400;\"> and <\/span><b>minimal pretreatment<\/b><span style=\"font-weight: 400;\"> required simplify application on various surfaces even in the presence of <\/span><b>moisture<\/b><span style=\"font-weight: 400;\"> or in <\/span><b>challenging environments<\/b><span style=\"font-weight: 400;\">.<\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;4&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;1&#8243;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2><strong>Discover all solutions in the ARALDITE\u00ae range<\/strong><\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<span style=\"font-weight: 400;\">To  <\/span><b>learn more<\/b><span style=\"font-weight: 400;\"> the <\/span><b>applications  <\/b><span style=\"font-weight: 400;\"> and the  <\/span><b>solutions  <\/b><span style=\"font-weight: 400;\">in the  <\/span><a href=\"https:\/\/mascherpa.it\/guida-prodotto\/marchi\/araldite\/\"><b>ARALDITE\u00ae<\/b><\/a><span style=\"font-weight: 400;\"> range, you can  <\/span><a href=\"https:\/\/mascherpa.it\/en\/contact\/\"><b>contact<\/b><\/a><span style=\"font-weight: 400;\">  directly with the  <\/span><b>Mascherpa experts,  <\/b><span style=\"font-weight: 400;\">who<\/span><b>  will  <\/b><span style=\"font-weight: 400;\">support you in selecting the most suitable products for your application requirements and industry standards.<\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/mascherpa.it\/en\/blog\/36871\/\" class=\"excerpt\">[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221;&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":36881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3338,5614,5582,3205,3324,3323],"tags":[3499],"class_list":{"0":"post-36871","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-aerospace-and-defense","8":"category-araldite-en-2","9":"category-huntsman","10":"category-industrial-adhesives","11":"category-methacrylic-adhesives","12":"category-structural-adhesives","13":"tag-mascherpa-en"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ARALDITE\u00ae 2051 A\/B approved ECS 7409 Airbus Helicopters<\/title>\n<meta name=\"description\" content=\"The ARALDITE\u00ae 2051 A\/B methacrylic adhesive for structural bonding in the aerospace sector has been approved ECS 7409 Airbus Helicopters.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mascherpa.it\/en\/blog\/36871\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARALDITE\u00ae 2051 A\/B approved ECS 7409 Airbus Helicopters\" \/>\n<meta property=\"og:description\" content=\"The ARALDITE\u00ae 2051 A\/B methacrylic adhesive for structural bonding in the aerospace sector has been approved ECS 7409 Airbus Helicopters.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mascherpa.it\/en\/blog\/36871\/\" \/>\n<meta property=\"og:site_name\" content=\"Mascherpa s.p.a\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-02T09:00:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-02T14:01:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mascherpa.it\/wp-content\/uploads\/2025\/12\/DSC09791-200x300.jpg\" \/>\n<meta name=\"author\" content=\"Mascherpa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/mascherpa.it\/wp-content\/uploads\/2025\/12\/DSC09791-683x1024.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mascherpa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/\"},\"author\":{\"name\":\"Mascherpa\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#\\\/schema\\\/person\\\/4eb665b7a59162f0f3162863f6eeac76\"},\"headline\":\"ARALDITE\u00ae 2051 A\\\/B approved ECS 7409 Airbus Helicopters\",\"datePublished\":\"2026-04-02T09:00:29+00:00\",\"dateModified\":\"2026-04-02T14:01:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/\"},\"wordCount\":2918,\"image\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mascherpa.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Airbus-Helicopters-.webp\",\"keywords\":[\"mascherpa\"],\"articleSection\":[\"Aerospace and Defense\",\"Araldite\",\"Huntsman\",\"Industrial Adhesives\",\"Methacrylic adhesives\",\"Structural adhesives\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/\",\"url\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/\",\"name\":\"ARALDITE\u00ae 2051 A\\\/B approved ECS 7409 Airbus Helicopters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mascherpa.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Airbus-Helicopters-.webp\",\"datePublished\":\"2026-04-02T09:00:29+00:00\",\"dateModified\":\"2026-04-02T14:01:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#\\\/schema\\\/person\\\/4eb665b7a59162f0f3162863f6eeac76\"},\"description\":\"The ARALDITE\u00ae 2051 A\\\/B methacrylic adhesive for structural bonding in the aerospace sector has been approved ECS 7409 Airbus Helicopters.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mascherpa.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Airbus-Helicopters-.webp\",\"contentUrl\":\"https:\\\/\\\/mascherpa.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Airbus-Helicopters-.webp\",\"width\":1536,\"height\":1024,\"caption\":\"Airbus Helicopters Araldite\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/36871\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"mascherpa.it\",\"item\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ARALDITE\u00ae 2051 A\\\/B approved ECS 7409 Airbus Helicopters\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/\",\"name\":\"Mascherpa s.p.a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#\\\/schema\\\/person\\\/4eb665b7a59162f0f3162863f6eeac76\",\"name\":\"Mascherpa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g\",\"caption\":\"Mascherpa\"},\"url\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/author\\\/mascherpa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARALDITE\u00ae 2051 A\/B approved ECS 7409 Airbus Helicopters","description":"The ARALDITE\u00ae 2051 A\/B methacrylic adhesive for structural bonding in the aerospace sector has been approved ECS 7409 Airbus Helicopters.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mascherpa.it\/en\/blog\/36871\/","og_locale":"en_US","og_type":"article","og_title":"ARALDITE\u00ae 2051 A\/B approved ECS 7409 Airbus Helicopters","og_description":"The ARALDITE\u00ae 2051 A\/B methacrylic adhesive for structural bonding in the aerospace sector has been approved ECS 7409 Airbus Helicopters.","og_url":"https:\/\/mascherpa.it\/en\/blog\/36871\/","og_site_name":"Mascherpa s.p.a","article_published_time":"2026-04-02T09:00:29+00:00","article_modified_time":"2026-04-02T14:01:49+00:00","og_image":[{"url":"https:\/\/mascherpa.it\/wp-content\/uploads\/2025\/12\/DSC09791-200x300.jpg","type":"","width":"","height":""}],"author":"Mascherpa","twitter_card":"summary_large_image","twitter_image":"https:\/\/mascherpa.it\/wp-content\/uploads\/2025\/12\/DSC09791-683x1024.jpg","twitter_misc":{"Written by":"Mascherpa","Est. reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mascherpa.it\/en\/blog\/36871\/#article","isPartOf":{"@id":"https:\/\/mascherpa.it\/en\/blog\/36871\/"},"author":{"name":"Mascherpa","@id":"https:\/\/mascherpa.it\/en\/#\/schema\/person\/4eb665b7a59162f0f3162863f6eeac76"},"headline":"ARALDITE\u00ae 2051 A\/B approved ECS 7409 Airbus Helicopters","datePublished":"2026-04-02T09:00:29+00:00","dateModified":"2026-04-02T14:01:49+00:00","mainEntityOfPage":{"@id":"https:\/\/mascherpa.it\/en\/blog\/36871\/"},"wordCount":2918,"image":{"@id":"https:\/\/mascherpa.it\/en\/blog\/36871\/#primaryimage"},"thumbnailUrl":"https:\/\/mascherpa.it\/wp-content\/uploads\/2026\/04\/Airbus-Helicopters-.webp","keywords":["mascherpa"],"articleSection":["Aerospace and Defense","Araldite","Huntsman","Industrial Adhesives","Methacrylic adhesives","Structural adhesives"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mascherpa.it\/en\/blog\/36871\/","url":"https:\/\/mascherpa.it\/en\/blog\/36871\/","name":"ARALDITE\u00ae 2051 A\/B approved ECS 7409 Airbus Helicopters","isPartOf":{"@id":"https:\/\/mascherpa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mascherpa.it\/en\/blog\/36871\/#primaryimage"},"image":{"@id":"https:\/\/mascherpa.it\/en\/blog\/36871\/#primaryimage"},"thumbnailUrl":"https:\/\/mascherpa.it\/wp-content\/uploads\/2026\/04\/Airbus-Helicopters-.webp","datePublished":"2026-04-02T09:00:29+00:00","dateModified":"2026-04-02T14:01:49+00:00","author":{"@id":"https:\/\/mascherpa.it\/en\/#\/schema\/person\/4eb665b7a59162f0f3162863f6eeac76"},"description":"The ARALDITE\u00ae 2051 A\/B methacrylic adhesive for structural bonding in the aerospace sector has been approved ECS 7409 Airbus Helicopters.","breadcrumb":{"@id":"https:\/\/mascherpa.it\/en\/blog\/36871\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mascherpa.it\/en\/blog\/36871\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mascherpa.it\/en\/blog\/36871\/#primaryimage","url":"https:\/\/mascherpa.it\/wp-content\/uploads\/2026\/04\/Airbus-Helicopters-.webp","contentUrl":"https:\/\/mascherpa.it\/wp-content\/uploads\/2026\/04\/Airbus-Helicopters-.webp","width":1536,"height":1024,"caption":"Airbus Helicopters Araldite"},{"@type":"BreadcrumbList","@id":"https:\/\/mascherpa.it\/en\/blog\/36871\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"mascherpa.it","item":"https:\/\/mascherpa.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/mascherpa.it\/en\/blog\/"},{"@type":"ListItem","position":3,"name":"ARALDITE\u00ae 2051 A\/B approved ECS 7409 Airbus Helicopters"}]},{"@type":"WebSite","@id":"https:\/\/mascherpa.it\/en\/#website","url":"https:\/\/mascherpa.it\/en\/","name":"Mascherpa s.p.a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mascherpa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/mascherpa.it\/en\/#\/schema\/person\/4eb665b7a59162f0f3162863f6eeac76","name":"Mascherpa","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78e7d5b344152700bc02b73308e122fb0301a3829dfbf744307f050c5d6022c1?s=96&d=mm&r=g","caption":"Mascherpa"},"url":"https:\/\/mascherpa.it\/en\/author\/mascherpa\/"}]}},"_links":{"self":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/posts\/36871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/comments?post=36871"}],"version-history":[{"count":6,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/posts\/36871\/revisions"}],"predecessor-version":[{"id":36888,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/posts\/36871\/revisions\/36888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/media\/36881"}],"wp:attachment":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/media?parent=36871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/categories?post=36871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/tags?post=36871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}