{"id":3499,"count":200,"description":"","link":"https:\/\/mascherpa.it\/en\/tag\/mascherpa-en\/","name":"mascherpa","slug":"mascherpa-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Articoli su mascherpa | Mascherpa s.p.a<\/title>\n<meta name=\"description\" content=\"Scopri tutti gli articoli su mascherpa di Mascherpa s.p.a. Contattaci per maggiori info.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mascherpa.it\/en\/tag\/mascherpa-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Articoli su mascherpa | Mascherpa s.p.a\" \/>\n<meta property=\"og:description\" content=\"Scopri tutti gli articoli su mascherpa di Mascherpa s.p.a. Contattaci per maggiori info.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mascherpa.it\/en\/tag\/mascherpa-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Mascherpa s.p.a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/tag\\\/mascherpa-en\\\/\",\"url\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/tag\\\/mascherpa-en\\\/\",\"name\":\"Articoli su mascherpa | Mascherpa s.p.a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#website\"},\"description\":\"Scopri tutti gli articoli su mascherpa di Mascherpa s.p.a. Contattaci per maggiori info.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/tag\\\/mascherpa-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/tag\\\/mascherpa-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"mascherpa.it\",\"item\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"mascherpa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/\",\"name\":\"Mascherpa s.p.a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mascherpa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Articoli su mascherpa | Mascherpa s.p.a","description":"Scopri tutti gli articoli su mascherpa di Mascherpa s.p.a. Contattaci per maggiori info.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mascherpa.it\/en\/tag\/mascherpa-en\/","og_locale":"en_US","og_type":"article","og_title":"Articoli su mascherpa | Mascherpa s.p.a","og_description":"Scopri tutti gli articoli su mascherpa di Mascherpa s.p.a. Contattaci per maggiori info.","og_url":"https:\/\/mascherpa.it\/en\/tag\/mascherpa-en\/","og_site_name":"Mascherpa s.p.a","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mascherpa.it\/en\/tag\/mascherpa-en\/","url":"https:\/\/mascherpa.it\/en\/tag\/mascherpa-en\/","name":"Articoli su mascherpa | Mascherpa s.p.a","isPartOf":{"@id":"https:\/\/mascherpa.it\/en\/#website"},"description":"Scopri tutti gli articoli su mascherpa di Mascherpa s.p.a. Contattaci per maggiori info.","breadcrumb":{"@id":"https:\/\/mascherpa.it\/en\/tag\/mascherpa-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/mascherpa.it\/en\/tag\/mascherpa-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"mascherpa.it","item":"https:\/\/mascherpa.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"mascherpa"}]},{"@type":"WebSite","@id":"https:\/\/mascherpa.it\/en\/#website","url":"https:\/\/mascherpa.it\/en\/","name":"Mascherpa s.p.a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mascherpa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/tags\/3499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mascherpa.it\/en\/wp-json\/wp\/v2\/posts?tags=3499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}